{"id":1953,"date":"2024-02-09T16:46:35","date_gmt":"2024-02-09T15:46:35","guid":{"rendered":"https:\/\/skyworkertrade.ch\/impressum\/"},"modified":"2024-03-24T13:37:46","modified_gmt":"2024-03-24T12:37:46","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"<div class=\"container\">\n\t<div class=\"row mt-n30 mt-md-n50  \">\n\t\t\t\t\t<div class=\"mt-30 mt-md-50 col-lg-12 \">\n\t\t\t\t<h1 class=\"h1  fw-700\">Mentions l\u00e9gales<\/h1>\n\t\t\t\t\t\t\t\t<div class=\"rich-text    \">\n\t\t\t\t\t\t\t\t\t<h2>\u00c9diteur<\/h2>\n<p>mateco AG<br \/>\nIfangstrasse 111<br \/>\n8153 R\u00fcmlang<br \/>\nTel. <a href=\"tel:0848484849\">0848 48 48 49<\/a><br \/>\n<a href=\"mailto:marketing@maltech.ch\">marketing@maltech.ch<\/a><\/p>\n<p>Registre de commerce: CHE-106.051.841<br \/>\nNum\u00e9ro d\u2019identification TVA: CHE-106.051.841 MWST<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Inscription au registre du commerce<\/strong><\/p>\n<p>Patrick Moser<br \/>\nCEO<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Num\u00e9ro de TVA<\/strong><\/p>\n<p>CHE-106.515.852<\/p>\n<h2><\/h2>\n<p>Limitation de responsabilit\u00e9<\/p>\n<p>Le contenu de ce site web est entretenu avec le plus grand soin. Nous ne pouvons n\u00e9anmoins pas assumer de responsabilit\u00e9 pour le contenu.<br \/>\nSous r\u00e9serve de fautes d\u2019impression, d\u2019erreurs et de modifications. Le contenu est prot\u00e9g\u00e9 par le droit d\u2019auteur. Nous n\u2019assumons pas de responsabilit\u00e9 pour le contenu des liens externes. La responsabilit\u00e9 du contenu des sites accessibles par un lien incombe exclusivement aux exploitants de ces sites.<\/p>\n<h2><\/h2>\n<h2><\/h2>\n<h2>Liens externes<\/h2>\n<p>Le site web contient des liens externes vers d\u2019autres sites, sur le contenu desquels l\u2019exploitant de ce site n\u2019a aucune influence. Pour ce motif, l\u2019exploitant de ces contenus ne peut pas assumer de garantie \u00e0 cet \u00e9gard.<br \/>\nL\u2019exploitant du site web vers lequel m\u00e8ne le lien assume la responsabilit\u00e9 exclusive des contenus et de l\u2019exactitude des informations mises \u00e0 disposition. Au moment de la mise en place du lien, aucune violation de la loi n\u2019\u00e9tait apparente. Le lien est imm\u00e9diatement supprim\u00e9 si une telle violation de la loi devient connue.<\/p>\n<h2><\/h2>\n<h2><\/h2>\n<h2>Droit d\u2019auteur et droit des marques<\/h2>\n<p>L\u2019exploitant de ce site web s\u2019efforce de respecter dans toutes les publications les droits d\u2019auteur des graphiques, des documents de son, des s\u00e9quences vid\u00e9o et des textes utilis\u00e9s, d\u2019utiliser des graphiques, des documents de son, des s\u00e9quences vid\u00e9o et des textes cr\u00e9\u00e9s par lui-m\u00eame ou de recourir \u00e0 des graphiques, des documents de son, des s\u00e9quences vid\u00e9o et des textes libres de licences. Toutes les marques nomm\u00e9es au sein de l\u2019offre sur internet, et \u00e9ventuellement d\u00e9pos\u00e9es par des tiers, sont soumises sans restriction aux dispositions du droit des marques applicable et aux droits de propri\u00e9t\u00e9 du propri\u00e9taire enregistr\u00e9. Le simple fait que ces marques soient mentionn\u00e9es ne permet pas de conclure qu\u2019elles ne sont pas prot\u00e9g\u00e9es par des droits de tiers!<\/p>\n<p>Le droit d\u2019auteur des objets publi\u00e9s et cr\u00e9\u00e9s par l\u2019exploitant lui-m\u00eame revient au seul exploitant de ces pages. La reproduction ou l\u2019utilisation de tels graphiques, documents de son, s\u00e9quences vid\u00e9o et textes dans d\u2019autres publications \u00e9lectroniques ou imprim\u00e9es ne sont pas permises sans le consentement explicite de l\u2019exploitant.<\/p>\n<p>&nbsp;<\/p>\n<p>Concept\/Design\/Programmation:<br \/>\nSTUIQ AG, Zurich<\/p>\n<p>Hosting\/Programmation de l&rsquo;interface (Tocco):<br \/>\nswipe GmbH, Frauenfeld<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":14503,"parent":0,"menu_order":999,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1953","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<title>Mentions l\u00e9gales - mateco AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mateco.ch\/fr\/mentions-legales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions l\u00e9gales - mateco AG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mateco.ch\/fr\/mentions-legales\/\" \/>\n<meta property=\"og:site_name\" content=\"mateco AG\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-24T12:37:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/08\/attachment-3089__maltech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/\",\"name\":\"Mentions l\u00e9gales - mateco AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/attachment-3089__maltech.jpg\",\"datePublished\":\"2024-02-09T15:46:35+00:00\",\"dateModified\":\"2024-03-24T12:37:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/attachment-3089__maltech.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/attachment-3089__maltech.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/mentions-legales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/\",\"name\":\"mateco AG\",\"description\":\"Ihr kompetenter Partner  rund um Arbeitsb\u00fchnen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#organization\",\"name\":\"mateco AG\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/mateco_logo-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/mateco_logo-scaled.png\",\"width\":2560,\"height\":653,\"caption\":\"mateco AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Mentions l\u00e9gales - mateco AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/","og_locale":"fr_FR","og_type":"article","og_title":"Mentions l\u00e9gales - mateco AG","og_url":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/","og_site_name":"mateco AG","article_modified_time":"2024-03-24T12:37:46+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/08\/attachment-3089__maltech.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/","url":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/","name":"Mentions l\u00e9gales - mateco AG","isPartOf":{"@id":"https:\/\/www.mateco.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/#primaryimage"},"image":{"@id":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/08\/attachment-3089__maltech.jpg","datePublished":"2024-02-09T15:46:35+00:00","dateModified":"2024-03-24T12:37:46+00:00","breadcrumb":{"@id":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mateco.ch\/fr\/mentions-legales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/#primaryimage","url":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/08\/attachment-3089__maltech.jpg","contentUrl":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/08\/attachment-3089__maltech.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.mateco.ch\/fr\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mateco.ch\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/www.mateco.ch\/fr\/#website","url":"https:\/\/www.mateco.ch\/fr\/","name":"mateco AG","description":"Ihr kompetenter Partner  rund um Arbeitsb\u00fchnen","publisher":{"@id":"https:\/\/www.mateco.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mateco.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mateco.ch\/fr\/#organization","name":"mateco AG","url":"https:\/\/www.mateco.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mateco.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/07\/mateco_logo-scaled.png","contentUrl":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/07\/mateco_logo-scaled.png","width":2560,"height":653,"caption":"mateco AG"},"image":{"@id":"https:\/\/www.mateco.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/pages\/1953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/comments?post=1953"}],"version-history":[{"count":10,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/pages\/1953\/revisions"}],"predecessor-version":[{"id":7547,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/pages\/1953\/revisions\/7547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/media\/14503"}],"wp:attachment":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/media?parent=1953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}