{"id":13727,"date":"2026-05-28T16:15:43","date_gmt":"2026-05-28T14:15:43","guid":{"rendered":"https:\/\/www.maltech.ch\/?post_type=references&#038;p=13727"},"modified":"2026-08-31T17:30:10","modified_gmt":"2026-08-31T15:30:10","slug":"technique-du-batiment-buttisholz-lu","status":"publish","type":"references","link":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/","title":{"rendered":"Technique du b\u00e2timent, Buttisholz LU"},"content":{"rendered":"<div class=\"container global-content-styles\">\n\n\t<div class=\"button-group d-inline-flex mt-0 mb-30\">\n\t<a href=\"\/fr\/societe-2\/references\/\" target=\"\" title=\"Retour aux r\u00e9sultats\" class=\"btn btn-primary btn-bg-mateco_red \" >\n\n  <i class=\"icon-chevron\"><\/i>\n      <span class=\"btn-text\">Retour aux r\u00e9sultats<\/span>\n  \n  \n<\/a>\n<\/div>\n\t    <div class=\"reference-media\">\n              <div class=\"position-relative swiper-maltech-style reference-detail-slider\">\n          <div class=\"swiper news-header-swiper\">\n            <div class=\"swiper-wrapper\">\n                              <div class=\"swiper-slide\">\n                                      <div class=\"img-wrapper\">\n                      \t\t<picture>\n\t\t\t\n\t\t\t<img width=\"768\" height=\"1024\" src=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-7-768x1024.jpg\" class=\"w-full h-auto\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-7-768x1024.jpg 768w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-7-225x300.jpg 225w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-7-1152x1536.jpg 1152w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-7-1536x2048.jpg 1536w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-7-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t<\/picture>\n\t\t                    <\/div>\n                                  <\/div>\n                              <div class=\"swiper-slide\">\n                                      <div class=\"img-wrapper\">\n                      \t\t<picture>\n\t\t\t\n\t\t\t<img width=\"768\" height=\"1024\" src=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-4-768x1024.jpg\" class=\"w-full h-auto\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-4-768x1024.jpg 768w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-4-225x300.jpg 225w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-4-1152x1536.jpg 1152w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-4-1536x2048.jpg 1536w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-4-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t<\/picture>\n\t\t                    <\/div>\n                                  <\/div>\n                              <div class=\"swiper-slide\">\n                                      <div class=\"img-wrapper\">\n                      \t\t<picture>\n\t\t\t\n\t\t\t<img width=\"768\" height=\"1024\" src=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-3-768x1024.jpg\" class=\"w-full h-auto\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-3-768x1024.jpg 768w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-3-225x300.jpg 225w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-3-1152x1536.jpg 1152w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-3-1536x2048.jpg 1536w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-3-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t<\/picture>\n\t\t                    <\/div>\n                                  <\/div>\n                              <div class=\"swiper-slide\">\n                                      <div class=\"img-wrapper\">\n                      \t\t<picture>\n\t\t\t\n\t\t\t<img width=\"1024\" height=\"768\" src=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-1-1024x768.jpg\" class=\"w-full h-auto\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-1-1024x768.jpg 1024w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-1-300x225.jpg 300w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-1-768x576.jpg 768w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-1-1536x1152.jpg 1536w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/image-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/picture>\n\t\t                    <\/div>\n                                  <\/div>\n                          <\/div>\n            <div class=\"swiper-pagination\"><\/div>\n          <\/div>\n          <div class=\"swiper-prev swiper-nav-btn news-header-swiper-btn\"><\/div>\n          <div class=\"swiper-next swiper-nav-btn news-header-swiper-btn\"><\/div>\n        <\/div>\n      \n      <aside class=\"reference-rebrand-notice reference-rebrand-notice--detail\" aria-label=\"Note concernant le changement de raison sociale\">\n\t<span class=\"reference-rebrand-notice__eyebrow\">Maltech est mateco.<\/span>\n\t<strong class=\"reference-rebrand-notice__title\">Tout reste meilleur.<\/strong>\n<\/aside>\n    <\/div>\n\t\n\t<h1 class=\"text-md-center mt-50\">Technique du b\u00e2timent, Buttisholz LU<\/h1>\n\n\t    <div class=\"row\">\n      <div class=\"col-md-10 offset-md-1 col-lg-8 offset-lg-2\">\n        <div class=\"rich-text lead mb-60 mb-md-100\">\n            <p>Certains projets sont tout sauf classiques, \u00e0 l&rsquo;image du nettoyage de l&rsquo;\u00e9glise de Buttisholz. Des man\u0153uvres au millim\u00e8tre pr\u00e8s, un espace restreint et l&rsquo;utilisation d\u2019un \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 HR 17 NE ont fait de cette mission un v\u00e9ritable d\u00e9fi. D\u00e9couvrez dans ce reportage passionnant comment l&rsquo;\u00e9quipe a relev\u00e9 ce d\u00e9fi, quel r\u00f4le joue le choix du bon \u00e9quipement et pourquoi l&rsquo;exp\u00e9rience est ici indispensable.<\/p>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\n\t    <div class=\"row\">\n      <div class=\"col-12 mb-n40 mb-md-n60\">\n                  <div class=\"row mb-40 mb-md-60\">\n            <div class=\"text col-md-10 offset-md-1 col-lg-8 offset-lg-2\">\n\n\t<h2 >L\u2019essentiel en chiffres et en faits<\/h2>\n\n\t    <div class=\"rich-text big-space-between\">\n\t\t\t<ul>\n<li>Temps de pr\u00e9paration : environ 1 an (planification, autorisations, conservation du patrimoine)<\/li>\n<li>\u00c9quipement utilis\u00e9 : 1 \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 HR 17 NE<\/li>\n<li>Plusieurs rendez-vous sur place : visites et r\u00e9unions de coordination<\/li>\n<li>Travaux sans interruption des activit\u00e9s : offices religieux, fun\u00e9railles, \u00e9v\u00e9nements<\/li>\n<li>Nettoyage complet de l&rsquo;int\u00e9rieur : plafonds, murs, statues, tableaux, lustres, fen\u00eatres, orgue<\/li>\n<li>Mesure suppl\u00e9mentaire : all\u00e8gement des tombes \u00e0 dalle en raison de leur poids<\/li>\n<li>Exigences \u00e9lev\u00e9es : espace restreint, mobilier fragile<\/li>\n<li>Exigences envers le personnel : ne pas avoir le vertige, \u00eatre pr\u00e9cis, \u00eatre form\u00e9 \u00e0 l&rsquo;utilisation des plateformes \u00e9l\u00e9vatrices<\/li>\n<\/ul>\n    <\/div>\n\t\n\t\n<\/div>          <\/div>\n                  <div class=\"row mb-40 mb-md-60\">\n            <div class=\"image col-md-10 offset-md-1 col-lg-8 offset-lg-2\">\n  <div class=\"img-wrapper mx-n30 mx-lg-0\" >\n\t\t\t\t<picture>\n\t\t\t\n\t\t\t<img width=\"800\" height=\"800\" src=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/armin-buehler-portrait.jpeg\" class=\"w-full h-auto\" alt=\"\u00a9 Maler Crivellotto AG\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/armin-buehler-portrait.jpeg 800w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/armin-buehler-portrait-300x300.jpeg 300w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/armin-buehler-portrait-150x150.jpeg 150w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/armin-buehler-portrait-768x768.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t<\/picture>\n\t\t  <\/div>\n  <div class=\"rich-text legende mt-10\">\n    <p>Armin B\u00fchler, Maler Crivellotto AG<\/p>\n  <\/div>\n<\/div>          <\/div>\n                  <div class=\"row mb-40 mb-md-60\">\n            <div class=\"interview col-md-10 offset-md-1 col-lg-8 offset-lg-2\">\n\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>La mission dans l&rsquo;\u00e9glise de Buttisholz \u00e9tait tout sauf standard. Quelle \u00e9tait la situation de d\u00e9part et quel \u00e9tait le plus grand d\u00e9fi ?<\/strong><\/p>\n\t\t\t\t\t<p>La situation de d\u00e9part \u00e9tait un int\u00e9rieur d\u00e9licat, avec un espace tr\u00e8s restreint et un mobilier \u00e0 prot\u00e9ger. Le plus grand d\u00e9fi consistait \u00e0 choisir la plateforme \u00e9l\u00e9vatrice adapt\u00e9e, en l\u2019occurrence un \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 HR 17 NE, tout en tenant compte des obstacles tels que l\u2019orgue ou les bancs d\u2019\u00e9glise. De plus, des travaux complexes de protection et de couverture ont \u00e9t\u00e9 n\u00e9cessaires. Le fonctionnement continu de l\u2019\u00e9glise, avec ses offices religieux, ses fun\u00e9railles et ses \u00e9v\u00e9nements, exigeait \u00e9galement une planification flexible et bien coordonn\u00e9e.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>Qu&rsquo;est-ce qui a \u00e9t\u00e9 nettoy\u00e9 exactement dans l&rsquo;\u00e9glise et pourquoi un \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 a-t-il \u00e9t\u00e9 utilis\u00e9 ? <\/strong><\/p>\n\t\t\t\t\t<p>Pratiquement tout l\u2019int\u00e9rieur a \u00e9t\u00e9 nettoy\u00e9 : les plafonds et les murs, ainsi que les statues, les tableaux, les lustres, les fen\u00eatres et l\u2019orgue. Pour ces travaux en hauteur et dans de nombreux endroits difficiles d\u2019acc\u00e8s, un \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 comme le HR 17 NE \u00e9tait id\u00e9ale. Il permet de travailler avec pr\u00e9cision m\u00eame au-del\u00e0 des obstacles tout en offrant la port\u00e9e et la stabilit\u00e9 n\u00e9cessaires.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>Man\u0153uvrer un \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 \u00e0 travers une porte d&rsquo;\u00e9glise et entre les bancs semble \u00eatre un travail de pr\u00e9cision. Comment s&rsquo;y prend-on concr\u00e8tement pour une telle intervention ?<\/strong><\/p>\n\t\t\t\t\t<p>De telles interventions exigent une pr\u00e9paration tr\u00e8s minutieuse et une \u00e9quipe bien rod\u00e9e. Plusieurs rep\u00e9rages sont effectu\u00e9s en amont afin de d\u00e9terminer le parcours optimal. Sur place, il faut ensuite man\u0153uvrer avec pr\u00e9cision, souvent dans un espace tr\u00e8s restreint. La collaboration avec des partenaires exp\u00e9riment\u00e9s tels que mateco est alors d\u00e9cisive. \u00c0 Buttisholz, il a fallu en outre soulager sp\u00e9cifiquement les dalles de sol en raison de la charge pond\u00e9rale.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>Quel r\u00f4le joue le choix de la bonne machine dans ce contexte ? Dans ce cas pr\u00e9cis, la HR 17 NE ?<\/strong><\/p>\n\t\t\t\t\t<p>Le choix de la bonne machine est essentiel pour la r\u00e9ussite globale du projet. La HR 17 NE offre exactement la combinaison de compacit\u00e9, de maniabilit\u00e9 et de port\u00e9e n\u00e9cessaire pour ce type de travaux en int\u00e9rieur. Un mauvais choix de machine aurait eu des r\u00e9percussions directes sur le temps, les co\u00fbts et la s\u00e9curit\u00e9.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>De telles interventions ne fonctionnent souvent qu\u2019en collaboration avec des partenaires. Comment s\u2019est d\u00e9roul\u00e9e concr\u00e8tement la coop\u00e9ration sur place ?<\/strong><\/p>\n\t\t\t\t\t<p>La collaboration a \u00e9t\u00e9 tr\u00e8s \u00e9troite et bien structur\u00e9e. D\u00e8s la phase de planification, des r\u00e9unions de coordination ont \u00e9t\u00e9 organis\u00e9es avec toutes les parties prenantes. Pendant l\u2019intervention, une communication claire a \u00e9t\u00e9 d\u00e9terminante, notamment en raison du fonctionnement continu de l\u2019\u00e9glise. Gr\u00e2ce \u00e0 l\u2019exp\u00e9rience de tous les partenaires, le d\u00e9roulement des op\u00e9rations a pu \u00eatre mis en \u0153uvre de mani\u00e8re efficace et sans heurts.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>Quelle exp\u00e9rience et quel doigt\u00e9 faut-il pour r\u00e9aliser des man\u0153uvres aussi pr\u00e9cises ? Selon vous, qu&rsquo;est-ce qui caract\u00e9rise un tr\u00e8s bon conducteur de plateforme \u00e9l\u00e9vatrice ?<\/strong><\/p>\n\t\t\t\t\t<p>Une telle intervention exige beaucoup d\u2019exp\u00e9rience et un haut degr\u00e9 de pr\u00e9cision. Outre une formation approfondie \u00e0 l\u2019utilisation de machines tels que la HR 17 NE, il est essentiel de ne pas avoir le vertige, d\u2019avoir des connaissances techniques et de garder son calme. Un bon conducteur de plateforme \u00e9l\u00e9vatrice anticipe, reste concentr\u00e9 m\u00eame dans les situations difficiles et agit en toute s\u00e9curit\u00e9 \u00e0 tout moment.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>Y a-t-il eu un moment pendant l\u2019intervention o\u00f9 vous vous \u00eates dit : \u00ab Bon, l\u00e0, \u00e7a va \u00eatre vraiment serr\u00e9 \u00bb ?<\/strong><\/p>\n\t\t\t\t\t<p>De tels moments surviennent r\u00e9guli\u00e8rement lors d\u2019interventions complexes, en particulier lors de passages \u00e9troits ou de positionnements difficiles. Cela d\u00e9pend aussi beaucoup de la forme du jour. Gr\u00e2ce \u00e0 une bonne pr\u00e9paration et \u00e0 notre exp\u00e9rience, nous avons toutefois pu ma\u00eetriser ces situations de mani\u00e8re contr\u00f4l\u00e9e \u00e0 tout moment \u2013 cela fait aussi partie de l\u2019attrait de ce m\u00e9tier.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>Un \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 de mateco a \u00e9t\u00e9 utilis\u00e9 lors de cette intervention. Qu&rsquo;est-ce qui vous convainc dans la collaboration avec mateco, en particulier pour des projets exigeants comme celui-ci ?<\/strong><\/p>\n\t\t\t\t\t<p>Notre collaboration de longue date avec mateco repose sur la confiance et la fiabilit\u00e9. C\u2019est justement dans les projets exigeants qu\u2019il est important de pouvoir compter sur le mat\u00e9riel et le partenaire. Avec mateco, nous avons toujours eu de tr\u00e8s bonnes exp\u00e9riences, tant au niveau du conseil que de la mise \u00e0 disposition des machines adapt\u00e9es, comme la HR 17 NE.<\/p>\n        <\/div>\n\t\t\t        <div class=\"rich-text\">\n          <p class=\"strong\"><strong>Quelle est l&rsquo;importance de la pr\u00e9paration et de la planification pour de tels projets ? Et quel r\u00f4le joue l&rsquo;exp\u00e9rience ?<\/strong><\/p>\n\t\t\t\t\t<p>La pr\u00e9paration est un facteur d\u00e9cisif. Dans le cas de Buttisholz, elle a dur\u00e9 environ un an et a n\u00e9cessit\u00e9 des concertations avec le conseil paroissial et les services de conservation des monuments historiques, ainsi que l\u2019obtention des autorisations et l\u2019organisation de la plateforme \u00e9l\u00e9vatrice. L\u2019exp\u00e9rience aide \u00e0 identifier rapidement les d\u00e9fis potentiels et \u00e0 d\u00e9velopper des solutions efficaces \u2013 elle est pratiquement indispensable dans ce type de projets.<\/p>\n        <\/div>\n\t\t\t<\/div>          <\/div>\n                  <div class=\"row mb-40 mb-md-60\">\n            <div class=\"cta-team col-12\">\n\n  \n  <div class=\"bg-transparent\">\n\t  \t  <div class=\"cta-team d-flex flex-column flex-md-row\">\n      <div class=\"img-wrapper\">\n\t\t  <img width=\"610\" height=\"610\" src=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2024\/03\/Benno_Betschart_2024_610x610px.jpg\" class=\"h-100\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2024\/03\/Benno_Betschart_2024_610x610px.jpg 610w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2024\/03\/Benno_Betschart_2024_610x610px-150x150.jpg 150w, https:\/\/www.mateco.ch\/wp-content\/uploads\/2024\/03\/Benno_Betschart_2024_610x610px-300x300.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/>    <\/div>\n  \t<div class=\"content p-20 p-md-40 p-lg-60 transparent d-flex align-items-center flex-fill\">\n    <div>\n\t    <h3 class=\"mb-10\">Chef de projet<\/h3>\n      <div class=\"rich-text\">\n                <p><span class=\"fw-700\">Benno Betschart, <\/span>Chef de projet<\/p>\n      <\/div>\n\t    <div class=\"button-group d-flex flex-column flex-lg-row mt-30\">\n\t<a href=\"mailto:projektleiter-ost@mateco.ch\" target=\"\" title=\"projektleiter-ost@mateco.ch\" class=\"btn btn-bg-mateco_red \" >\n\n  <i class=\"icon-mail\"><\/i>\n      <span class=\"btn-text\">projektleiter-ost@mateco.ch<\/span>\n  \n  \n<\/a>\n<a href=\"tel:0412810311\" target=\"\" title=\"041 281 03 11\" class=\"btn btn-bg-blue \" >\n\n  <i class=\"icon-phone\"><\/i>\n      <span class=\"btn-text\">041 281 03 11<\/span>\n  \n  \n<\/a>\n<\/div>    <\/div>\n\t<\/div>\n<\/div>\n  <\/div>\n<\/div>          <\/div>\n              <\/div>\n    <\/div>\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Certains projets sont tout sauf classiques, \u00e0 l&rsquo;image du nettoyage de l&rsquo;\u00e9glise de Buttisholz. Des man\u0153uvres au millim\u00e8tre pr\u00e8s, un espace restreint et l&rsquo;utilisation d\u2019un \u00e9l\u00e9vateur \u00e0 nacelle t\u00e9lescopique articul\u00e9 HR 17 NE ont fait de cette mission un v\u00e9ritable d\u00e9fi. D\u00e9couvrez dans ce reportage passionnant comment l&rsquo;\u00e9quipe a relev\u00e9 ce d\u00e9fi, quel r\u00f4le joue le choix du bon \u00e9quipement et pourquoi l&rsquo;exp\u00e9rience est ici indispensable.<\/p>\n","protected":false},"featured_media":13477,"template":"","application_areas_category":[106],"class_list":["post-13727","references","type-references","status-publish","has-post-thumbnail","hentry","application_areas_category-facility-management-und-gebaeudetechnik-fr"],"acf":[],"yoast_head":"<title>Technique du b\u00e2timent, Buttisholz LU - mateco AG<\/title>\n<meta name=\"description\" content=\"Schnelle Umsetzung, hohe Qualit\u00e4t und minimale Beeintr\u00e4chtigung des laufenden Betriebs: Photovoltaikprojekte f\u00fcr Industrie und Gewerbe stellen hohe Anforderungen an Planung und Logistik. Die Ampere Dynamic Schweiz GmbH setzt dabei auf flexible L\u00f6sungen \u2013 und erstmals auf Teleskopstapler von mateco. Projektleiter Livio Rivelli erkl\u00e4rt, warum das Zusammenspiel von Ger\u00e4t, Partner und Timing entscheidend ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technique du b\u00e2timent, Buttisholz LU - mateco AG\" \/>\n<meta property=\"og:description\" content=\"Manche Projekte sind alles andere als Standard \u2013 so wie die Reinigung in der Kirche Buttisholz. Millimetergenaue Man\u00f6ver, eine enge Umgebung und der Einsatz einer Gelenkteleskopb\u00fchne HR 17 NE machten diesen Job zur Herausforderung. Wie das Team diese Aufgabe meisterte, welche Rolle das richtige Ger\u00e4t spielt und warum Erfahrung hier unverzichtbar ist, erfahren Sie im spannenden Bericht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/\" \/>\n<meta property=\"og:site_name\" content=\"mateco AG\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T15:30:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/anzeigebild-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/\",\"name\":\"Technique du b\u00e2timent, Buttisholz LU - mateco AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/anzeigebild-2.jpg\",\"datePublished\":\"2026-05-28T14:15:43+00:00\",\"dateModified\":\"2026-08-31T15:30:10+00:00\",\"description\":\"Schnelle Umsetzung, hohe Qualit\u00e4t und minimale Beeintr\u00e4chtigung des laufenden Betriebs: Photovoltaikprojekte f\u00fcr Industrie und Gewerbe stellen hohe Anforderungen an Planung und Logistik. Die Ampere Dynamic Schweiz GmbH setzt dabei auf flexible L\u00f6sungen \u2013 und erstmals auf Teleskopstapler von mateco. Projektleiter Livio Rivelli erkl\u00e4rt, warum das Zusammenspiel von Ger\u00e4t, Partner und Timing entscheidend ist.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/anzeigebild-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/anzeigebild-2.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/societe\\\/references\\\/technique-du-batiment-buttisholz-lu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technique du b\u00e2timent, Buttisholz LU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/\",\"name\":\"mateco AG\",\"description\":\"Ihr kompetenter Partner  rund um Arbeitsb\u00fchnen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#organization\",\"name\":\"mateco AG\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/mateco_logo-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.mateco.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/mateco_logo-scaled.png\",\"width\":2560,\"height\":653,\"caption\":\"mateco AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mateco.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Technique du b\u00e2timent, Buttisholz LU - mateco AG","description":"Schnelle Umsetzung, hohe Qualit\u00e4t und minimale Beeintr\u00e4chtigung des laufenden Betriebs: Photovoltaikprojekte f\u00fcr Industrie und Gewerbe stellen hohe Anforderungen an Planung und Logistik. Die Ampere Dynamic Schweiz GmbH setzt dabei auf flexible L\u00f6sungen \u2013 und erstmals auf Teleskopstapler von mateco. Projektleiter Livio Rivelli erkl\u00e4rt, warum das Zusammenspiel von Ger\u00e4t, Partner und Timing entscheidend ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/","og_locale":"fr_FR","og_type":"article","og_title":"Technique du b\u00e2timent, Buttisholz LU - mateco AG","og_description":"Manche Projekte sind alles andere als Standard \u2013 so wie die Reinigung in der Kirche Buttisholz. Millimetergenaue Man\u00f6ver, eine enge Umgebung und der Einsatz einer Gelenkteleskopb\u00fchne HR 17 NE machten diesen Job zur Herausforderung. Wie das Team diese Aufgabe meisterte, welche Rolle das richtige Ger\u00e4t spielt und warum Erfahrung hier unverzichtbar ist, erfahren Sie im spannenden Bericht.","og_url":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/","og_site_name":"mateco AG","article_modified_time":"2026-08-31T15:30:10+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/anzeigebild-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/","url":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/","name":"Technique du b\u00e2timent, Buttisholz LU - mateco AG","isPartOf":{"@id":"https:\/\/www.mateco.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/#primaryimage"},"image":{"@id":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/anzeigebild-2.jpg","datePublished":"2026-05-28T14:15:43+00:00","dateModified":"2026-08-31T15:30:10+00:00","description":"Schnelle Umsetzung, hohe Qualit\u00e4t und minimale Beeintr\u00e4chtigung des laufenden Betriebs: Photovoltaikprojekte f\u00fcr Industrie und Gewerbe stellen hohe Anforderungen an Planung und Logistik. Die Ampere Dynamic Schweiz GmbH setzt dabei auf flexible L\u00f6sungen \u2013 und erstmals auf Teleskopstapler von mateco. Projektleiter Livio Rivelli erkl\u00e4rt, warum das Zusammenspiel von Ger\u00e4t, Partner und Timing entscheidend ist.","breadcrumb":{"@id":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/#primaryimage","url":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/anzeigebild-2.jpg","contentUrl":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/04\/anzeigebild-2.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.mateco.ch\/fr\/societe\/references\/technique-du-batiment-buttisholz-lu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mateco.ch\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Technique du b\u00e2timent, Buttisholz LU"}]},{"@type":"WebSite","@id":"https:\/\/www.mateco.ch\/fr\/#website","url":"https:\/\/www.mateco.ch\/fr\/","name":"mateco AG","description":"Ihr kompetenter Partner  rund um Arbeitsb\u00fchnen","publisher":{"@id":"https:\/\/www.mateco.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mateco.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mateco.ch\/fr\/#organization","name":"mateco AG","url":"https:\/\/www.mateco.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mateco.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/07\/mateco_logo-scaled.png","contentUrl":"https:\/\/www.mateco.ch\/wp-content\/uploads\/2026\/07\/mateco_logo-scaled.png","width":2560,"height":653,"caption":"mateco AG"},"image":{"@id":"https:\/\/www.mateco.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/references\/13727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/references"}],"about":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/types\/references"}],"version-history":[{"count":3,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/references\/13727\/revisions"}],"predecessor-version":[{"id":15438,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/references\/13727\/revisions\/15438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/media\/13477"}],"wp:attachment":[{"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/media?parent=13727"}],"wp:term":[{"taxonomy":"application_areas_category","embeddable":true,"href":"https:\/\/www.mateco.ch\/fr\/wp-json\/wp\/v2\/application_areas_category?post=13727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}